{"id":91,"date":"2022-06-11T10:17:00","date_gmt":"2022-06-11T10:17:00","guid":{"rendered":"http:\/\/inspirythemesdemo.com\/realplaces\/?post_type=property&#038;p=91"},"modified":"2022-12-19T18:47:51","modified_gmt":"2022-12-19T18:47:51","slug":"villa-on-grand-avenue","status":"publish","type":"property","link":"https:\/\/di.realhomes.io\/ultra\/property\/villa-on-grand-avenue\/","title":{"rendered":"Villa on Grand Avenue"},"content":{"rendered":"\n<p>Spacious and fabulous home in prime location. This executive style four bed, four bath home has impact resistant windows, renovated kitchen with wood cabinets, granite countertops and luminous breakfast area. All bathrooms are tastefully redone with contemporary elements and vanities.<\/p>\n\n\n\n<p>Open floor plan leads to the patio, pool and backyard for great entertainment or relaxation. Live in the city beautiful, enjoy the best shopping, restaurants, schools, and much more this home offers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spacious and fabulous home in prime location. This executive style four bed, four bath home has impact resistant windows, renovated kitchen with wood cabinets, granite countertops and luminous breakfast area. All bathrooms are tastefully redone with contemporary elements and vanities. Open floor plan leads to the patio, pool and backyard for great entertainment or relaxation&#8230;.<\/p>\n","protected":false},"author":6,"featured_media":4610,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-features":[32,53,34,35,37,48,49,40,50],"property-types":[54],"property-cities":[41],"property-statuses":[47],"class_list":["post-91","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-2-stories","property-feature-central-cooling","property-feature-dual-sinks","property-feature-electric-range","property-feature-fire-place","property-feature-home-theater","property-feature-laundry-room","property-feature-marble-floors","property-feature-swimming-pool","property-type-villa","property-city-miami","property-status-for-rent"],"property_meta":{"REAL_HOMES_property_price":"4750","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"Monthly","REAL_HOMES_property_size":"9350","REAL_HOMES_property_size_postfix":"sq ft","REAL_HOMES_property_lot_size":"9800","REAL_HOMES_property_lot_size_postfix":"sq ft","REAL_HOMES_property_bedrooms":"4","REAL_HOMES_property_bathrooms":"4","REAL_HOMES_property_garage":"2","REAL_HOMES_property_id":"RH-2017-09","REAL_HOMES_property_year_built":"2018","rvr_property_owner":"","REAL_HOMES_featured":"1","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"25.728020152188","longitude":"-80.245112335474","zoom":"14"},"REAL_HOMES_property_address":"CocoWalk, 3015 Grand Avenue, Miami, USA","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2020\/06\/House-Design.jpg","filesize":167081,"sizes":{"medium":{"file":"House-Design-300x174.jpg","width":300,"height":174,"mime-type":"image\/jpeg","filesize":15997,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-300x174.jpg"},"large":{"file":"House-Design-1024x595.jpg","width":1024,"height":595,"mime-type":"image\/jpeg","filesize":115874,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-1024x595.jpg"},"thumbnail":{"file":"House-Design-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8609,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-150x150.jpg"},"medium_large":{"file":"House-Design-768x446.jpg","width":768,"height":446,"mime-type":"image\/jpeg","filesize":71831,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-768x446.jpg"},"post-thumbnail":{"file":"House-Design-150x87.jpg","width":150,"height":87,"mime-type":"image\/jpeg","filesize":5950,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-150x87.jpg"},"modern-property-child-slider":{"file":"House-Design-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":69932,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-680x510.jpg"},"property-thumb-image":{"file":"House-Design-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":37461,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-488x326.jpg"},"property-detail-video-image":{"file":"House-Design-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":70894,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-818x417.jpg"},"agent-image":{"file":"House-Design-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":14294,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-210x210.jpg"},"partners-logo":{"file":"House-Design-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":88616,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-600x720.jpg"},"post-featured-image":{"file":"House-Design-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":165671,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"4610","name":"House-Design.jpg","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design.jpg","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-150x150.jpg","full_url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design.jpg","title":"House-Design","caption":"","description":"","alt":"","srcset":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-150x150.jpg 150w, https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/House-Design-210x210.jpg 210w"},{"width":150,"height":150,"file":"2020\/06\/house-02.jpg","filesize":238307,"sizes":{"medium":{"file":"house-02-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":18511,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-300x169.jpg"},"large":{"file":"house-02-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":149876,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-1024x576.jpg"},"thumbnail":{"file":"house-02-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8964,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-150x150.jpg"},"medium_large":{"file":"house-02-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":93005,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-768x432.jpg"},"post-thumbnail":{"file":"house-02-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":5730,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-150x84.jpg"},"modern-property-child-slider":{"file":"house-02-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":93740,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-680x510.jpg"},"property-thumb-image":{"file":"house-02-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":48385,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-488x326.jpg"},"property-detail-video-image":{"file":"house-02-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":96809,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-818x417.jpg"},"agent-image":{"file":"house-02-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":15887,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-210x210.jpg"},"partners-logo":{"file":"house-02-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":110972,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-600x720.jpg"},"post-featured-image":{"file":"house-02-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":231329,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"4612","name":"house-02.jpg","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02.jpg","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-150x150.jpg","full_url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02.jpg","title":"house-02","caption":"","description":"","alt":"","srcset":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-150x150.jpg 150w, https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/house-02-210x210.jpg 210w"},{"width":150,"height":150,"file":"2020\/06\/bathroom-00.jpg","filesize":164486,"sizes":{"medium":{"file":"bathroom-00-300x175.jpg","width":300,"height":175,"mime-type":"image\/jpeg","filesize":9749,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-300x175.jpg"},"large":{"file":"bathroom-00-1024x596.jpg","width":1024,"height":596,"mime-type":"image\/jpeg","filesize":64921,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-1024x596.jpg"},"thumbnail":{"file":"bathroom-00-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5222,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-150x150.jpg"},"medium_large":{"file":"bathroom-00-768x447.jpg","width":768,"height":447,"mime-type":"image\/jpeg","filesize":41134,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-768x447.jpg"},"post-thumbnail":{"file":"bathroom-00-150x87.jpg","width":150,"height":87,"mime-type":"image\/jpeg","filesize":3605,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-150x87.jpg"},"modern-property-child-slider":{"file":"bathroom-00-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":42941,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-680x510.jpg"},"property-thumb-image":{"file":"bathroom-00-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":23105,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-488x326.jpg"},"property-detail-video-image":{"file":"bathroom-00-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":41699,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-818x417.jpg"},"agent-image":{"file":"bathroom-00-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8769,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-210x210.jpg"},"partners-logo":{"file":"bathroom-00-600x722.jpg","width":600,"height":722,"mime-type":"image\/jpeg","filesize":55732,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-600x722.jpg"},"post-featured-image":{"file":"bathroom-00-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":88168,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"4604","name":"bathroom-00.jpg","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00.jpg","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-150x150.jpg","full_url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00.jpg","title":"bathroom-00","caption":"","description":"","alt":"","srcset":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-150x150.jpg 150w, https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bathroom-00-210x210.jpg 210w"},{"width":150,"height":150,"file":"2020\/06\/bedroom-04.jpg","filesize":211156,"sizes":{"medium":{"file":"bedroom-04-300x174.jpg","width":300,"height":174,"mime-type":"image\/jpeg","filesize":13778,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-300x174.jpg"},"large":{"file":"bedroom-04-1024x595.jpg","width":1024,"height":595,"mime-type":"image\/jpeg","filesize":125307,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-1024x595.jpg"},"thumbnail":{"file":"bedroom-04-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7085,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-150x150.jpg"},"medium_large":{"file":"bedroom-04-768x446.jpg","width":768,"height":446,"mime-type":"image\/jpeg","filesize":73561,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-768x446.jpg"},"post-thumbnail":{"file":"bedroom-04-150x87.jpg","width":150,"height":87,"mime-type":"image\/jpeg","filesize":4352,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-150x87.jpg"},"modern-property-child-slider":{"file":"bedroom-04-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":77970,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-680x510.jpg"},"property-thumb-image":{"file":"bedroom-04-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":37070,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-488x326.jpg"},"property-detail-video-image":{"file":"bedroom-04-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":74495,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-818x417.jpg"},"agent-image":{"file":"bedroom-04-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":12838,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-210x210.jpg"},"partners-logo":{"file":"bedroom-04-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":120595,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-600x720.jpg"},"post-featured-image":{"file":"bedroom-04-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":205384,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"4605","name":"bedroom-04.jpg","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04.jpg","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-150x150.jpg","full_url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04.jpg","title":"bedroom-04","caption":"","description":"","alt":"","srcset":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-150x150.jpg 150w, https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/bedroom-04-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[{"inspiry_floor_plan_name":"1 Bedroom Apartment","inspiry_floor_plan_descr":"A walk-in closet and a bathroom with a vanity, toilet, and walk-in shower are also included in the attached bedroom.","inspiry_floor_plan_price":"$300","inspiry_floor_plan_price_postfix":"Per Night","inspiry_floor_plan_size":"654","inspiry_floor_plan_size_postfix":"sq ft","inspiry_floor_plan_bedrooms":"1","inspiry_floor_plan_bathrooms":"1","inspiry_floor_plan_image":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2022\/06\/1Bedroom-2d.jpg"}],"inspiry_video_group":[{"inspiry_video_group_image":"4937","inspiry_video_group_title":"Video Tour","inspiry_video_group_url":"https:\/\/www.youtube.com\/watch?v=uTIcquf4Z-s"}],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_agent_display_option":"agent_info","REAL_HOMES_agents":["57"],"REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"","inspiry_additional_fee":"","REAL_HOMES_attachments":[{"filesize":12426,"ID":"4816","name":"Ultra-Demo.docx","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2022\/06\/Ultra-Demo.docx","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2022\/06\/Ultra-Demo.docx","title":"Ultra Demo Word File"},{"sizes":{"full":{"file":"Ultra-Demo-pdf.jpg","width":1088,"height":1408,"mime-type":"image\/jpeg","filesize":19978},"medium":{"file":"Ultra-Demo-pdf-232x300.jpg","width":232,"height":300,"mime-type":"image\/jpeg","filesize":4560},"large":{"file":"Ultra-Demo-pdf-791x1024.jpg","width":791,"height":1024,"mime-type":"image\/jpeg","filesize":12412},"thumbnail":{"file":"Ultra-Demo-pdf-116x150.jpg","width":116,"height":150,"mime-type":"image\/jpeg","filesize":3313}},"filesize":16966,"ID":"4817","name":"Ultra-Demo.pdf","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2022\/06\/Ultra-Demo.pdf","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2022\/06\/Ultra-Demo.pdf","title":"Ultra Demo PDF File"},{"filesize":8806,"ID":"4818","name":"Ultra-Demo.xlsx","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2022\/06\/Ultra-Demo.xlsx","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2022\/06\/Ultra-Demo.xlsx","title":"Ultra Demo Excel File"},{"width":1200,"height":800,"file":"2022\/11\/placeholder.png","filesize":6146,"sizes":{"medium":{"file":"placeholder-300x200.png","width":300,"height":200,"mime-type":"image\/png","filesize":2092},"large":{"file":"placeholder-1024x683.png","width":1024,"height":683,"mime-type":"image\/png","filesize":7582},"thumbnail":{"file":"placeholder-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":1264},"medium_large":{"file":"placeholder-768x512.png","width":768,"height":512,"mime-type":"image\/png","filesize":5437},"post-thumbnail":{"file":"placeholder-150x100.png","width":150,"height":100,"mime-type":"image\/png","filesize":1105},"modern-property-child-slider":{"file":"placeholder-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":4883},"property-thumb-image":{"file":"placeholder-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":3341},"property-detail-video-image":{"file":"placeholder-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":5541},"agent-image":{"file":"placeholder-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":1661},"partners-logo":{"file":"placeholder-600x800.png","width":600,"height":800,"mime-type":"image\/png","filesize":3276}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"155","name":"placeholder.png","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2022\/11\/placeholder.png","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2022\/11\/placeholder.png","title":"Ultra Demo Image File"}],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[{"width":150,"height":150,"file":"2020\/06\/villa-on-grand-slider.jpg","filesize":253192,"sizes":{"medium":{"file":"villa-on-grand-slider-300x172.jpg","width":300,"height":172,"mime-type":"image\/jpeg","filesize":13221,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-300x172.jpg"},"large":{"file":"villa-on-grand-slider-1024x588.jpg","width":1024,"height":588,"mime-type":"image\/jpeg","filesize":85540,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-1024x588.jpg"},"thumbnail":{"file":"villa-on-grand-slider-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7271,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-150x150.jpg"},"medium_large":{"file":"villa-on-grand-slider-768x441.jpg","width":768,"height":441,"mime-type":"image\/jpeg","filesize":53710,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-768x441.jpg"},"1536x1536":{"file":"villa-on-grand-slider-1536x883.jpg","width":1536,"height":883,"mime-type":"image\/jpeg","filesize":163792,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-1536x883.jpg"},"post-thumbnail":{"file":"villa-on-grand-slider-150x86.jpg","width":150,"height":86,"mime-type":"image\/jpeg","filesize":5179,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-150x86.jpg"},"modern-property-child-slider":{"file":"villa-on-grand-slider-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":55082,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-680x510.jpg"},"property-thumb-image":{"file":"villa-on-grand-slider-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":29427,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-488x326.jpg"},"property-detail-video-image":{"file":"villa-on-grand-slider-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":54662,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-818x417.jpg"},"agent-image":{"file":"villa-on-grand-slider-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":11647,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-210x210.jpg"},"partners-logo":{"file":"villa-on-grand-slider-600x1132.jpg","width":600,"height":1132,"mime-type":"image\/jpeg","filesize":97913,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-600x1132.jpg"},"post-featured-image":{"file":"villa-on-grand-slider-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":117200,"url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"4776","name":"villa-on-grand-slider.jpg","path":"\/sites\/di.realhomes.io\/files\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider.jpg","url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-150x150.jpg","full_url":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider.jpg","title":"villa-on-grand-slider","caption":"","description":"","alt":"","srcset":"https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-150x150.jpg 150w, https:\/\/di.realhomes.io\/ultra\/wp-content\/uploads\/sites\/20\/2020\/06\/villa-on-grand-slider-210x210.jpg 210w"}],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_custom_header_display":"default","REAL_HOMES_custom_header_position":"relative","REAL_HOMES_custom_footer_display":"default","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":""},"_links":{"self":[{"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/properties\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":1,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/properties\/91\/revisions"}],"predecessor-version":[{"id":4613,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/properties\/91\/revisions\/4613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/media\/4610"}],"wp:attachment":[{"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/media?parent=91"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/property-features?post=91"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/property-types?post=91"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/property-cities?post=91"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/di.realhomes.io\/ultra\/wp-json\/wp\/v2\/property-statuses?post=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}